{"id":2633,"date":"2024-10-01T13:06:23","date_gmt":"2024-10-01T13:06:23","guid":{"rendered":"https:\/\/sendaecoway.com\/vuelta-al-cole"},"modified":"2024-10-14T07:39:23","modified_gmt":"2024-10-14T07:39:23","slug":"rentree-scolaire","status":"publish","type":"post","link":"https:\/\/sendaecoway.com\/fr\/blog\/vuelta-al-cole\/","title":{"rendered":"Rentr\u00e9e scolaire"},"content":{"rendered":"<p>L&#039;\u00e9t\u00e9 et les exp\u00e9riences qu&#039;il offre sont \u00e9troitement li\u00e9s aux vacances, aux loisirs et au plaisir des adultes et des enfants qui se retrouvent avec des heures et des heures de temps libre \u00e0 savourer.<\/p>\n<p>Si nous nous concentrons un peu, nous pouvons tous encore ressentir ce trac \u00e0 l&#039;id\u00e9e de retourner \u00e0 l&#039;\u00e9cole. <strong>Retrouver ses amis, rencontrer de nouveaux professeurs et relever de nouveaux d\u00e9fis. <\/strong> Il est fr\u00e9quent d&#039;\u00e9prouver ce m\u00e9lange de nouveaut\u00e9 et de frustration lorsque l&#039;on constate que la discipline et la routine reviennent dans nos vies tandis que la merveilleuse \u201c libert\u00e9 \u201d des interminables journ\u00e9es d&#039;\u00e9t\u00e9 est laiss\u00e9e derri\u00e8re nous.<\/p>\n<div data-rt-embed-type='true'><link href=\"https:\/\/fonts.googleapis.com\/icon?family=Material+Icons\" rel=\"stylesheet\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\"><\/p>\n<style>\n.myDiv {\nmargin-left: 15px;\n \u00a0border-radius: 5px;\n \u00a0background-color:#bdd5d4;\n \u00a0text-align: left;\n \u00a0border:2px solid #539796;\n}\n.textstyle{\nfont-family: Arial, Helvetica, sans-serif;\nfont-size:15px;\n}\n.underline{\ncolor:#539796;\ntext-decoration: none;\n}<\/p>\n<p>.imgstyle{\nborder-radius: 5px;\nwidth:100%;<\/p>\n<p>}\n.textt{\ntext-align:left;\nmargin-top:30px;\nmargin-left:20px;\nwidth:100%;\n}\n.space{\nmargin-left:20px;\nmargin-right:20px;\n}<\/p>\n<p>.styledivvs{\ndisplay:inline-block;\nvertical-align:top;\nfloat:center;\n}\n.styledivvs2{\ndisplay:inline-block;\nbackground-color:#fff;\nheight:130px;\nwidth:140px;\nborder-radius:5px;\npadding-top:40px;\n}\n.container{\nalign-content:center;\ntext-align:center;\npadding-bottom:20px;\ntransition: all 0.5s linear;\n}<\/p>\n<p>\/*.container:hover{\ntransform:scale(1,1);\n}*\/\n.container:hover {\n \u00a0transform: scale(1.1);\n}<\/p>\n<p>.material-icons{\npadding-top:20px;\n}\na:hover {\ntext-decoration: underline;\ncolor:#175453;\n}<\/p>\n<\/style>\n<div class=\"myDiv\">\n<p> \u00a0<\/p>\n<p class=\"textt\"><b><span class=\"material-icons\"><br \/>\n \u00a0ampoule<\/span>Quel plan suivre pour vos vacances ?<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Ne manquez pas l'exp\u00e9rience <b>Excursion au sommet du Teide : \u00e0 pied ou en t\u00e9l\u00e9ph\u00e9rique<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Explorez le parc national le plus visit\u00e9 d&#039;Europe et gravissez le plus haut sommet d&#039;Espagne. Repoussez vos limites lors de cette excursion. <b>ascension du sommet du Teide avec les permis n\u00e9cessaires.<\/b><\/p>\n<p class=\"space\">Si vous souhaitez vivre une exp\u00e9rience unique et respectueuse de l&#039;environnement, et d\u00e9couvrir le parc national du Teide, class\u00e9 au patrimoine mondial, avec l&#039;aide d&#039;un guide Senda, alors cette offre est faite pour vous. <b>Site du patrimoine mondial de l&#039;UNESCO<\/b>, R\u00e9servez votre place pour un <a class=\"underline\" href=\"https:\/\/sendaecoway.com\/fr\/experiences\/excursion-pico-teide\/\">Visite guid\u00e9e du mont Teide avec permis.<\/a><\/p>\n<div class=\"container\">\n \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img decoding=\"async\" class=\"imgstyle\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/61f2bf8b1fb5c74a13e68d08_parque-nacional-teide-senderismo-evento-twf2015.jpeg\" alt=\"Teide\" \u00a0width=\"130\" height=\"130\"><br \/>\n \u00a0 \u00a0 \u00a0<\/div>\n<p> \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs2\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p class=\"textstyle\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a class=\"underline\" href=\"https:\/\/sendaecoway.com\/fr\/experiences\/excursion-pico-teide\/\">D\u00e9couvrez une exp\u00e9rience unique.<\/a><br \/>\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p> \u00a0 \u00a0 \u00a0<\/p><\/div>\n<p> \u00a0<\/p><\/div>\n<\/div>\n<\/div>\n<h2>Des exp\u00e9riences familiales uniques et inoubliables<\/h2>\n<p>La rentr\u00e9e scolaire approche, et c&#039;est pr\u00e9cis\u00e9ment \u00e0 ce moment-l\u00e0 que nous faisons un bilan mental, un inventaire intime pour savoir si nous avons \u00e9t\u00e9 \u00e0 la hauteur de notre besoin de vivre un \u00e9t\u00e9 hors du commun.<\/p>\n<p>Au-del\u00e0 des voyages au long cours, nous d\u00e9cidons parfois de profiter de l&#039;\u00e9t\u00e9 dans notre propre pays. Cette ann\u00e9e, <strong>Je garderai en m\u00e9moire les exp\u00e9riences uniques que j&#039;ai v\u00e9cues. &nbsp;<\/strong>Parmi tous ces moments, on compte de formidables conversations, des ap\u00e9ritifs \u00e0 n&#039;en plus finir et des couchers de soleil magnifiques. Je vais vous parler d&#039;un moment qui m&#039;a particuli\u00e8rement surpris. Cet \u00e9t\u00e9, j&#039;ai eu la chance de nager avec des tortues en famille, sur le sentier. <a href=\"https:\/\/sendaecoway.com\/fr\/sendas\/snorkeling-con-avistamiento-de-tortugas-y-mantarrayas\/\">Faire de la plong\u00e9e avec tuba parmi les tortues et les raies manta.<\/a><\/p>\n<p>Cette exp\u00e9rience s&#039;est d\u00e9marqu\u00e9e de toutes les autres pour de nombreuses raisons. La principale est que c&#039;\u00e9tait quelque chose que je n&#039;avais jamais fait auparavant et, pour \u00eatre honn\u00eate, je ne savais pas que c&#039;\u00e9tait possible dans les eaux de <a href=\"https:\/\/es.wikipedia.org\/wiki\/Tenerife\">Tenerife<\/a>. Nager avec ces animaux, les respecter et les admirer dans leur libert\u00e9 de mouvement, est une sensation inestimable.<\/p>\n<p>De plus, durant l&#039;activit\u00e9, le moniteur qui nous accompagnait nous a transmis sa passion pour la plong\u00e9e, pour le<strong> la faune et le respect des fonds marins. <\/strong>Cela a sans aucun doute contribu\u00e9 \u00e0 rendre ce moment unique de nager avec nos ch\u00e8res tortues de Tenerife inoubliable. Nous savons qu&#039;elles migreront un jour, mais pour l&#039;instant, elles font partie int\u00e9grante de l&#039;\u00e9t\u00e9 de notre famille, et c&#039;est un souvenir que nous garderons pr\u00e9cieusement !<\/p>\n<p>C\u2019est la rentr\u00e9e scolaire, et avec elle l\u2019automne, les jours raccourcissent et nous rangeons temporairement nos maillots de bain. Cependant, ma famille et moi garderons un \u0153il sur\u2026 <strong>nouvelles propositions pour la saison <\/strong>pour continuer \u00e0 profiter d&#039;exp\u00e9riences touristiques uniques et incomparables.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le retour \u00e0 l&#039;\u00e9cole \u2764\ufe0f nous remplit de nostalgie pour l&#039;\u00e9t\u00e9, mais nous nous souviendrons toujours des exp\u00e9riences uniques v\u00e9cues en famille.<\/p>","protected":false},"author":2,"featured_media":2634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-2633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vuelta al cole - Senda Ecoway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaecoway.com\/fr\/blog\/rentree-scolaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vuelta al cole - Senda Ecoway\" \/>\n<meta property=\"og:description\" content=\"La vuelta al cole \u2764\ufe0f nos transmite el sentimiento de nostalgia del verano pero siempre recordaremos las experiencias \u00fanicas vividas en familia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaecoway.com\/fr\/blog\/rentree-scolaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Ecoway\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T13:06:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T07:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MarSen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarSen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"},\"author\":{\"name\":\"MarSen\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\"},\"headline\":\"La vuelta al cole\",\"datePublished\":\"2024-10-01T13:06:23+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\",\"name\":\"La vuelta al cole - Senda Ecoway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"datePublished\":\"2024-10-01T13:06:23+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"width\":400,\"height\":250,\"caption\":\"La vuelta al cole - Experiencias a tope\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vuelta al cole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"name\":\"Senda Ecoway\",\"description\":\"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendaecoway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\",\"name\":\"senda ecoway\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"width\":1024,\"height\":413,\"caption\":\"senda ecoway\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\",\"name\":\"MarSen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"caption\":\"MarSen\"},\"url\":\"https:\\\/\\\/sendaecoway.com\\\/fr\\\/blog\\\/author\\\/marsen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rentr\u00e9e scolaire - Sentier Ecoway","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaecoway.com\/fr\/blog\/rentree-scolaire\/","og_locale":"fr_FR","og_type":"article","og_title":"La vuelta al cole - Senda Ecoway","og_description":"La vuelta al cole \u2764\ufe0f nos transmite el sentimiento de nostalgia del verano pero siempre recordaremos las experiencias \u00fanicas vividas en familia.","og_url":"https:\/\/sendaecoway.com\/fr\/blog\/rentree-scolaire\/","og_site_name":"Senda Ecoway","article_published_time":"2024-10-01T13:06:23+00:00","article_modified_time":"2024-10-14T07:39:23+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","type":"image\/jpeg"}],"author":"MarSen","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"MarSen","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#article","isPartOf":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"},"author":{"name":"MarSen","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52"},"headline":"La vuelta al cole","datePublished":"2024-10-01T13:06:23+00:00","dateModified":"2024-10-14T07:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","articleSection":["blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/","url":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/","name":"Rentr\u00e9e scolaire - Sentier Ecoway","isPartOf":{"@id":"https:\/\/sendaecoway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","datePublished":"2024-10-01T13:06:23+00:00","dateModified":"2024-10-14T07:39:23+00:00","breadcrumb":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","width":400,"height":250,"caption":"La vuelta al cole - Experiencias a tope"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaecoway.com\/"},{"@type":"ListItem","position":2,"name":"La vuelta al cole"}]},{"@type":"WebSite","@id":"https:\/\/sendaecoway.com\/#website","url":"https:\/\/sendaecoway.com\/","name":"Chemin d'Ecoway","description":"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.","publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaecoway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/sendaecoway.com\/#organization","name":"senda ecoway","url":"https:\/\/sendaecoway.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","width":1024,"height":413,"caption":"senda ecoway"},"image":{"@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52","name":"MarSen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","url":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","caption":"MarSen"},"url":"https:\/\/sendaecoway.com\/fr\/blog\/author\/marsen\/"}]}},"_links":{"self":[{"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/posts\/2633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/comments?post=2633"}],"version-history":[{"count":1,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/posts\/2633\/revisions"}],"predecessor-version":[{"id":3038,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/posts\/2633\/revisions\/3038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/media\/2634"}],"wp:attachment":[{"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/media?parent=2633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/categories?post=2633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendaecoway.com\/fr\/wp-json\/wp\/v2\/tags?post=2633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}