{"id":1162,"date":"2024-09-09T20:25:36","date_gmt":"2024-09-09T20:25:36","guid":{"rendered":"https:\/\/sendaecoway.com\/?post_type=product&#038;p=1162"},"modified":"2026-03-04T10:20:18","modified_gmt":"2026-03-04T10:20:18","slug":"surf-el-medano-tenerife-tauchen-sie-ein-in-die-wellen","status":"publish","type":"product","link":"https:\/\/sendaecoway.com\/de\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/","title":{"rendered":"Tauchen Sie ein in die Wellen des Surfens in El M\u00e9dano, Teneriffa"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid arielrow vc_custom_1723063122323 vc_row-has-fill vc_column-gap-5 vc_row-o-content-middle vc_row-flex et_custom_uniqid_new_66b3db4d39e1a mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-10 et_custom_uniqid_new_66b3bde36bfa7 mpc-column\" data-column-id=\"mpc_column-46a9889dfc48c4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1725913585673\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><img decoding=\"async\" class=\"alignnone size-full wp-image-849\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/08\/Group-36108.png\" alt=\"\" width=\"65\" height=\"60\" srcset=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/08\/Group-36108.png 65w, https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/08\/Group-36108-10x10.png 10w\" sizes=\"(max-width: 65px) 100vw, 65px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<h1 style=\"font-size: 50px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1723573964680\">Sumergete en las Olas del Surf en El M&eacute;dano, Tenerife<\/h1><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-2 align-end et_custom_uniqid_new_66c4d40c6c1e3 mpc-column\" data-column-id=\"mpc_column-876a9889dfc4ef3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><p style=\"font-size: 21px;color: #bcd1cb;line-height: 35px;text-align: right\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1724175354958\">DESDE<\/p>\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1725913650427 damprice\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"load-turitop\" data-service=\"P294\" data-lang=\"es\" data-embed=\"button\"><span class=\"woocommerce-Price-amount amount\"><bdi>60<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/div>  \n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1723063189758 vc_row-has-fill vc_row-no-padding et_custom_uniqid_new_66b3db918b0db mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 et_custom_uniqid_new_66b3db76ae293 mpc-column\" data-column-id=\"mpc_column-866a9889dfe81be\"><div class=\"vc_column-inner vc_custom_1723063164054\"><div class=\"wpb_wrapper\">        <link rel=\"stylesheet\" href=\"https:\/\/sendaecoway.com\/wp-content\/themes\/xstore\/css\/modules\/builders\/wpb\/images-carousel.min.css?ver=9.7.7\" type=\"text\/css\" media=\"all\"> \t\t\t<div class=\"swiper-entry wpb_images_carousel wpb_content_element.vc_custom_1747212939893{margin-top: 0px !important;padding-top: 0px !important;} vc_clearfix\">\n\t\t<div class=\"swiper-container carousel-7116\" data-breakpoints=\"3\" data-xs-slides=\"1\" data-sm-slides=\"3\" data-md-slides=\"3\" data-lt-slides=\"3\" data-slides-per-view=\"3\" data-autoplay=\"5000\" data-loop=\"\">\n\t\t\t<!-- Wrapper for slides -->\n\t\t\t<div class=\"swiper-wrapper swiper-images-carousel\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e909f70c6d2e5b1141271__DSC1073.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e909f70c6d2e5b1141271__DSC1073.jpg\" width=\"550\" height=\"405\" alt=\"Surf el M&eacute;dano Tenerife\" title=\"651e909f70c6d2e5b1141271__DSC1073\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2a0331025ef95b7b7__DSC0970.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2a0331025ef95b7b7__DSC0970-448x425.jpg\" width=\"448\" height=\"425\" alt=\"651e90b2a0331025ef95b7b7__DSC0970\" title=\"651e90b2a0331025ef95b7b7__DSC0970\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b216f00ab82afde6b0__DSC0965.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b216f00ab82afde6b0__DSC0965-459x425.jpg\" width=\"459\" height=\"425\" alt=\"Surf el M&eacute;dano Tenerife\" title=\"651e90b216f00ab82afde6b0__DSC0965\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b28da88bc5e076948d__DSC0958.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b28da88bc5e076948d__DSC0958-450x425.jpg\" width=\"450\" height=\"425\" alt=\"Surf el M&eacute;dano Tenerife\" title=\"651e90b28da88bc5e076948d__DSC0958\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2f94d11e3230dc091_DSC_7364.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2f94d11e3230dc091_DSC_7364.jpg\" width=\"550\" height=\"366\" alt=\"651e90b2f94d11e3230dc091_DSC_7364\" title=\"651e90b2f94d11e3230dc091_DSC_7364\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2f94d11e3230dc077_DSC_3552-1.jpeg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2f94d11e3230dc077_DSC_3552-1.jpeg\" width=\"550\" height=\"366\" alt=\"Surf el M&eacute;dano Tenerife\" title=\"651e90b2f94d11e3230dc077_DSC_3552 (1)\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2331d4d5b1afc75e9_DSC_1788.jpeg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b2331d4d5b1afc75e9_DSC_1788.jpeg\" width=\"500\" height=\"333\" alt=\"651e90b2331d4d5b1afc75e9_DSC_1788\" title=\"651e90b2331d4d5b1afc75e9_DSC_1788\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b26633d9c3e0ff5485_DSC_1778.jpeg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b26633d9c3e0ff5485_DSC_1778.jpeg\" width=\"550\" height=\"366\" alt=\"651e90b26633d9c3e0ff5485_DSC_1778\" title=\"651e90b26633d9c3e0ff5485_DSC_1778\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"prettyphoto\" href=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b1f94d11e3230dc022__DSC4260.jpg\" data-rel=\"prettyPhoto[rel-1162-3266687232]\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/651e90b1f94d11e3230dc022__DSC4260.jpg\" width=\"550\" height=\"419\" alt=\"Surf el M&eacute;dano Tenerife\" title=\"651e90b1f94d11e3230dc022__DSC4260\" loading=\"lazy\">\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n            \n                <div class=\"swiper-custom-left\"><\/div>\n                <div class=\"swiper-custom-right\"><\/div>\n            \t\t<\/div>\n\t<\/div>\n\t\n\t<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-35 et_custom_uniqid_new_66bb9e689265c mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-8 et_custom_uniqid_6a9889de37cb7 mpc-column\" data-column-id=\"mpc_column-876a9889dfeab61\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-tabs vc_tta-color-peacoc vc_tta-style-modern vc_tta-shape-rounded vc_tta-spacing-3 vc_tta-o-no-fill vc_tta-tabs-position-top vc_tta-controls-align-left\"><div class=\"vc_tta-tabs-container\"><ul class=\"vc_tta-tabs-list\"><li class=\"vc_tta-tab vc_active\" data-vc-tab><a href=\"#1723571265005-29edd586-772d\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Descripci&oacute;n<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1723570910080-ceaec1bd-265e\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Detalle<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1723570910097-4d781908-0a80\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">&iquest;Que incluye?<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1723571363037-038b24c3-6c10\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Ubicaci&oacute;n<\/span><\/a><\/li><li class=\"vc_tta-tab\" data-vc-tab><a href=\"#1747213414625-ef899f3a-4374\" data-vc-tabs data-vc-container=\".vc_tta\"><span class=\"vc_tta-title-text\">Preguntas Frecuentes<\/span><\/a><\/li><\/ul><\/div><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"1723571265005-29edd586-772d\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1723571265005-29edd586-772d\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Descripci&oacute;n<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><h2 style=\"font-size: 30px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1723573807861\">Descripci&oacute;n<\/h2>\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1747215045338\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"descripci-n-experiencia w-richtext\">\n<h2><strong>Surf en El M&eacute;dano, Tenerife<\/strong><\/h2>\n<p>Nada se compara con la sensaci&oacute;n de deslizarte sobre una ola y dejarte llevar por la energ&iacute;a del mar. Ven y experimenta la magia del <span data-sheets-root=\"1\">Surf en el M&eacute;dano en Tenerife<\/span>, sumergi&eacute;ndote en un mundo de diversi&oacute;n acu&aacute;tica sin fin.<\/p>\n<p><a href=\"https:\/\/sendaecoway.com\/experiencias\/sumergete-en-las-olas-del-surf-en-el-medano\/\">Ofrecemos<\/a>&nbsp;lecciones de surf adaptadas a tus necesidades y habilidades. De esta forma, nuestros experimentados instructores te guiar&aacute;n paso a paso para que puedas aprender y disfrutar del surf de manera segura y divertida. Ya seas un principiante emocionado por probar este emocionante deporte acu&aacute;tico, o un surfista experimentado en busca de nuevas olas, tenemos opciones para todos los niveles. Adem&aacute;s, la playa cuenta con una gran infraestructura, con restaurantes y zonas de descanso donde podr&aacute;s relajarte despu&eacute;s de un d&iacute;a de surf.<\/p>\n<h3 data-start=\"846\" data-end=\"895\"><strong data-start=\"849\" data-end=\"895\">El M&eacute;dano: Disfruta de las mejores olas<\/strong><\/h3>\n<p data-start=\"897\" data-end=\"1187\">El M&eacute;dano es una de las playas m&aacute;s emblem&aacute;ticas de Tenerife, conocida por su ambiente relajado y su belleza natural. Con una extensi&oacute;n de aproximadamente 2 km de arena dorada, es la playa m&aacute;s larga de la isla y un lugar ideal para la pr&aacute;ctica del surf.<\/p>\n<p data-start=\"1189\" data-end=\"1359\">La playa est&aacute; flanqueada por la Monta&ntilde;a Roja, un cono volc&aacute;nico que ofrece vistas espectaculares y es una <a href=\"https:\/\/www.tenerife.es\/w\/reserva-natural-especial-montana-roja?redirect=%2Finstrumentos-de-ordenacion-de-los-espacios-naturales-protegidos-de-canarias\">reserva natural protegida<\/a>.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1723570910080-ceaec1bd-265e\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1723570910080-ceaec1bd-265e\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Detalle<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><h2 style=\"font-size: 30px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1725715115794\">Detalle<\/h2>\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1772619609048 tabledescrip\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table style=\"height: 195px;\" width=\"544\">\n<tbody>\n<tr>\n<td><i class=\"far fa-clock\"><\/i> <strong><span style=\"color: #33cccc;\">Horario<\/span><\/strong><\/td>\n<td>10.30 h, 12.00 h, 13.00 h, 15.00 h, 16.00 h<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-globe\"><\/i> <strong><span style=\"color: #33cccc;\">Idioma<\/span><\/strong><\/td>\n<td>Espa&ntilde;ol, Ingl&eacute;s, Franc&eacute;s e Italiano<\/td>\n<\/tr>\n<tr>\n<td><i class=\"far fa-clock\"><\/i><strong> <span style=\"color: #33cccc;\">Duraci&oacute;n<\/span><\/strong><\/td>\n<td>2h<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-users\"><\/i><strong><span style=\"color: #33cccc;\">N&uacute;mero de personas<\/span><\/strong><\/td>\n<td>A partir de 1 persona, m&aacute;ximo&nbsp; de 3 a 4 personas.<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-check\"><\/i><strong><span style=\"color: #33cccc;\">Ideal para<\/span><\/strong><\/td>\n<td>Amigos, Familias, Parejas<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-hourglass-half\"><\/i><strong><span style=\"color: #33cccc;\">Antelaci&oacute;n de la reserva<\/span><\/strong><\/td>\n<td>2 d&iacute;as<\/td>\n<\/tr>\n<tr>\n<td><i class=\"fa fa-map-marker-alt\"><\/i><strong><span style=\"color: #33cccc;\">Localizaci&oacute;n<\/span><\/strong><\/td>\n<td>El M&eacute;dano<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1723570910097-4d781908-0a80\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1723570910097-4d781908-0a80\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">&iquest;Que incluye?<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><h2 style=\"font-size: 30px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1725715131546\">&iquest;Que incluye?<\/h2>\n\t<div class=\"wpb_text_column wpb_content_element vc_custom_1725914010761 tabledescrip\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Este paquete incluye:<\/p>\n<ul role=\"list\">\n<li><strong>Compromiso Senda Ecoway:<\/strong>&nbsp;La actividad se realiza con el m&iacute;nimo impacto a la fauna marina<\/li>\n<li><strong>Equipo de &nbsp;Surf completo:&nbsp;<\/strong>Tabla adecuada a la persona<\/li>\n<li><strong>Seguro de la actividad.<\/strong><\/li>\n<li><strong>Instructor experto<\/strong><\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1723571363037-038b24c3-6c10\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1723571363037-038b24c3-6c10\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Ubicaci&oacute;n<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><h2 style=\"font-size: 30px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1725715162117\">Ubicaci&oacute;n<\/h2>\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1725914035672\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d5566.447207291146!2d-16.542676!3d28.041504!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xc6a9fe4ced8c849%3A0x1648c8b23c9a8217!2sPaseo%20Ntra.%20Sra.%20de%20las%20Mercedes%20de%20Roja%2C%2054%2C%2038612%20El%20M%C3%A9dano%2C%20Santa%20Cruz%20de%20Tenerife!5e1!3m2!1ses!2ses!4v1725914020235!5m2!1ses!2ses\" width=\"100%\" height=\"600\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><div class=\"vc_tta-panel\" id=\"1747213414625-ef899f3a-4374\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title\"><a href=\"#1747213414625-ef899f3a-4374\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Preguntas Frecuentes<\/span><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\"><h2 style=\"font-size: 30px;color: #000000;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\">Preguntas Frecuentes<\/h2><div class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&iquest;Qu&eacute; tipo de olas tiene la playa de El M&eacute;dano?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>El M&eacute;dano es conocida por sus olas suaves y consistentes, lo que la hace perfecta para los principiantes. Sin embargo, tambi&eacute;n tiene olas m&aacute;s grandes para surfistas con experiencia. Es un lugar ideal para todos los niveles.<\/p>\n<\/div><\/div><div class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&iquest;Cu&aacute;l es la edad m&iacute;nima para tomar clases de surf?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>La edad m&iacute;nima var&iacute;a seg&uacute;n la escuela de surf, pero en general, los ni&ntilde;os a partir de 6 a&ntilde;os pueden comenzar a aprender bajo la supervisi&oacute;n de un instructor cualificado.<\/p>\n<\/div><\/div><div class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&iquest;Cu&aacute;ndo es la mejor &eacute;poca para practicar surf en El M&eacute;dano?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p data-start=\"1365\" data-end=\"1592\">El M&eacute;dano tiene condiciones ideales durante todo el a&ntilde;o, pero la mejor &eacute;poca para surfear suele ser en oto&ntilde;o e invierno, cuando las olas son m&aacute;s consistentes.<\/p>\n<\/div><\/div><div class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&iquest;Cu&aacute;nto tiempo dura cada clase de surf?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p data-start=\"699\" data-end=\"906\">Cada clase tiene una duraci&oacute;n de aproximadamente 2 horas. Esto incluye una parte te&oacute;rica en tierra y tiempo en el agua para practicar las t&eacute;cnicas aprendidas.<\/p>\n<\/div><\/div><div class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&iquest;Qu&eacute; debo llevar a las clases de surf?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Te recomendamos traer ropa c&oacute;moda para estar en la playa (como ba&ntilde;ador o traje de ba&ntilde;o), protector solar, toalla y una botella de agua. Nosotros proporcionamos todo el equipo necesario, como la tabla de surf y el neopreno.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4 et_custom_uniqid_6a9889de37cb7 mpc-column\" data-column-id=\"mpc_column-336a9889dfeb09b\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1772452876820 reservar\" id=\"reservar\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"load-turitop\" data-service=\"P294\" data-lang=\"es\" data-embed=\"box\">Reservar ahora<\/div>  \n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element vc_custom_1727965305430 reservar turifix\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"load-turitop\" data-service=\"P294\" data-lang=\"es\" data-embed=\"button\">Reservar ahora<\/div>  \n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1723063279081 vc_row-has-fill et_custom_uniqid_new_66b3dbeba6e30 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 et_custom_uniqid_6a9889de37cb7 mpc-column\" data-column-id=\"mpc_column-506a9889dfebe66\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid et_custom_uniqid_6a9889de37c24 mpc-row\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-has-fill et_custom_uniqid_new_66bb9e44db924 mpc-column\" data-column-id=\"mpc_column-696a9889dfebd22\"><div class=\"vc_column-inner vc_custom_1723571788880\"><div class=\"wpb_wrapper\"><p style=\"font-size: 20px;color: #ffffff;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\">COMPENSAMOS TU HUELLA DE CARBONO<\/p><h2 style=\"font-size: 46px;color: #ffffff;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading vc_custom_1725914051448\">Con esta actividad compensamos 32kg de CO2<\/h2><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Sumergete en las Olas del Surf en El M&eacute;dano, TenerifeDESDE 60&euro; Descripci&oacute;nDetalle&iquest;Que incluye?Ubicaci&oacute;nPreguntas FrecuentesDescripci&oacute;nDescripci&oacute;n Surf en El M&eacute;dano, Tenerife Nada se compara con la sensaci&oacute;n...","protected":false},"featured_media":3442,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"etheme_brands":[],"product_brand":[],"product_cat":[33,40],"product_tag":[],"class_list":["post-1162","product","type-product","status-publish","has-post-thumbnail","product_cat-canarias","product_cat-tenerife","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife<\/title>\n<meta name=\"description\" content=\"Descubre el surf en El M\u00e9dano, Tenerife. Lecciones para todos los niveles, con instructores especializados. \u00a1Disfruta de las mejores olas de la isla!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/surf-el-medano-tenerife-tauchen-sie-ein-in-die-wellen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife\" \/>\n<meta property=\"og:description\" content=\"Descubre el surf en El M\u00e9dano, Tenerife. Lecciones para todos los niveles, con instructores especializados. \u00a1Disfruta de las mejores olas de la isla!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/surf-el-medano-tenerife-tauchen-sie-ein-in-die-wellen\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Ecoway\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T10:20:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/26.png\" \/>\n\t<meta property=\"og:image:width\" content=\"339\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/\",\"name\":\"Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26.png\",\"datePublished\":\"2024-09-09T20:25:36+00:00\",\"dateModified\":\"2026-03-04T10:20:18+00:00\",\"description\":\"Descubre el surf en El M\u00e9dano, Tenerife. Lecciones para todos los niveles, con instructores especializados. \u00a1Disfruta de las mejores olas de la isla!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/26.png\",\"width\":339,\"height\":543,\"caption\":\"Surf el M\u00e9dano Tenerife\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/surf-el-medano-tenerife-sumergete-en-las-olas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"experiencias\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/experiencias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"name\":\"Senda Ecoway\",\"description\":\"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendaecoway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\",\"name\":\"senda ecoway\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"width\":1024,\"height\":413,\"caption\":\"senda ecoway\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tauchen Sie ein in die Wellen des Surfens in El M\u00e9dano, Teneriffa","description":"Entdecken Sie das Surfen in El M\u00e9dano, Teneriffa. Kurse f\u00fcr alle Niveaus, mit spezialisierten Lehrern, genie\u00dfen Sie die besten Wellen auf der Insel!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaecoway.com\/de\/erfahrungen\/surf-el-medano-tenerife-tauchen-sie-ein-in-die-wellen\/","og_locale":"de_DE","og_type":"article","og_title":"Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife","og_description":"Descubre el surf en El M\u00e9dano, Tenerife. Lecciones para todos los niveles, con instructores especializados. \u00a1Disfruta de las mejores olas de la isla!","og_url":"https:\/\/sendaecoway.com\/de\/erfahrungen\/surf-el-medano-tenerife-tauchen-sie-ein-in-die-wellen\/","og_site_name":"Senda Ecoway","article_modified_time":"2026-03-04T10:20:18+00:00","og_image":[{"width":339,"height":543,"url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/26.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/","url":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/","name":"Tauchen Sie ein in die Wellen des Surfens in El M\u00e9dano, Teneriffa","isPartOf":{"@id":"https:\/\/sendaecoway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/#primaryimage"},"image":{"@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/26.png","datePublished":"2024-09-09T20:25:36+00:00","dateModified":"2026-03-04T10:20:18+00:00","description":"Entdecken Sie das Surfen in El M\u00e9dano, Teneriffa. Kurse f\u00fcr alle Niveaus, mit spezialisierten Lehrern, genie\u00dfen Sie die besten Wellen auf der Insel!","breadcrumb":{"@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/#primaryimage","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/26.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/09\/26.png","width":339,"height":543,"caption":"Surf el M\u00e9dano Tenerife"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaecoway.com\/experiencias\/surf-el-medano-tenerife-sumergete-en-las-olas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaecoway.com\/"},{"@type":"ListItem","position":2,"name":"experiencias","item":"https:\/\/sendaecoway.com\/experiencias\/"},{"@type":"ListItem","position":3,"name":"Sumergete en las Olas del Surf en El M\u00e9dano, Tenerife"}]},{"@type":"WebSite","@id":"https:\/\/sendaecoway.com\/#website","url":"https:\/\/sendaecoway.com\/","name":"Ecoway Pfad","description":"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.","publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaecoway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sendaecoway.com\/#organization","name":"senda ecoway","url":"https:\/\/sendaecoway.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","width":1024,"height":413,"caption":"senda ecoway"},"image":{"@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product\/1162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/comments?post=1162"}],"version-history":[{"count":2,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product\/1162\/revisions"}],"predecessor-version":[{"id":6055,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product\/1162\/revisions\/6055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media\/3442"}],"wp:attachment":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media?parent=1162"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/etheme_brands?post=1162"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product_brand?post=1162"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product_cat?post=1162"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/product_tag?post=1162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}