{"id":2633,"date":"2024-10-01T13:06:23","date_gmt":"2024-10-01T13:06:23","guid":{"rendered":"https:\/\/sendaecoway.com\/vuelta-al-cole"},"modified":"2024-10-14T07:39:23","modified_gmt":"2024-10-14T07:39:23","slug":"zuruck-zur-schule","status":"publish","type":"post","link":"https:\/\/sendaecoway.com\/de\/blog\/vuelta-al-cole\/","title":{"rendered":"Zur\u00fcck zur Schule"},"content":{"rendered":"<p>Der Sommer und die damit verbundenen Erlebnisse sind eng mit Urlaub, Freizeit und dem Vergn\u00fcgen von Erwachsenen und Kindern verbunden, die stundenlang freie Zeit zur Verf\u00fcgung haben.<\/p>\n<p>Wenn wir uns ein wenig konzentrieren, k\u00f6nnen wir alle noch immer dieses Kribbeln im Bauch sp\u00fcren, wenn wir wieder zur Schule gehen. <strong>Das Wiedersehen mit Freunden und die Begegnung mit neuen Lehrern und Herausforderungen. <\/strong> Es ist ein h\u00e4ufiges Gef\u00fchl, eine Mischung aus Neuheit und Frustration zu empfinden, wenn wir feststellen, dass Disziplin und Routine in unser Leben zur\u00fcckkehren, w\u00e4hrend die wunderbare &quot;Wildheit&quot; der endlosen Sommertage hinter uns gelassen wird.<\/p>\n<div data-rt-embed-type='true'><link href=\"https:\/\/fonts.googleapis.com\/icon?family=Material+Icons\" rel=\"stylesheet\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\"><\/p>\n<style>\n.myDiv {\nmargin-left: 15px;\n \u00a0border-radius: 5px;\n \u00a0background-color:#bdd5d4;\n \u00a0text-align: left;\n \u00a0border:2px solid #539796;\n}\n.textstyle{\nfont-family: Arial, Helvetica, sans-serif;\nfont-size:15px;\n}\n.underline{\ncolor:#539796;\ntext-decoration: none;\n}<\/p>\n<p>.imgstyle{\nborder-radius: 5px;\nwidth:100%;<\/p>\n<p>}\n.textt{\ntext-align:left;\nmargin-top:30px;\nmargin-left:20px;\nwidth:100%;\n}\n.space{\nmargin-left:20px;\nmargin-right:20px;\n}<\/p>\n<p>.styledivvs{\ndisplay:inline-block;\nvertical-align:top;\nfloat:center;\n}\n.styledivvs2{\ndisplay:inline-block;\nbackground-color:#fff;\nheight:130px;\nwidth:140px;\nborder-radius:5px;\npadding-top:40px;\n}\n.container{\nalign-content:center;\ntext-align:center;\npadding-bottom:20px;\ntransition: all 0.5s linear;\n}<\/p>\n<p>\/*.container:hover{\ntransform:scale(1,1);\n}*\/\n.container:hover {\n \u00a0transform: scale(1.1);\n}<\/p>\n<p>.material-icons{\npadding-top:20px;\n}\na:hover {\ntext-decoration: underline;\ncolor:#175453;\n}<\/p>\n<\/style>\n<div class=\"myDiv\">\n<p> \u00a0<\/p>\n<p class=\"textt\"><b><span class=\"material-icons\"><br \/>\n \u00a0Gl\u00fchbirne<\/span>Welchem Plan folgen Sie in Ihrem Urlaub?<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Verpassen Sie nicht das Erlebnis <b>Ausflug zum Teide-Gipfel: zu Fu\u00df oder mit der Seilbahn<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Lernen Sie den meistbesuchten Nationalpark Europas kennen und besteigen Sie den h\u00f6chsten Gipfel Spaniens. \u00dcberschreiten Sie Ihre Grenzen auf diesem Ausflug von <b>Besteigung des Gipfels des Teide mit Genehmigung.<\/b><\/p>\n<p class=\"space\">Wenn Sie ein einzigartiges und umweltfreundliches Erlebnis erleben und au\u00dferdem mit einem Senda-F\u00fchrer den Teide-Nationalpark kennen lernen m\u00f6chten, der von der UNESCO zum Weltkulturerbe erkl\u00e4rt wurde, dann sind Sie hier genau richtig. <b>Unesco-Welterbe<\/b>buchen Sie Ihren Platz f\u00fcr eine <a class=\"underline\" href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/excursion-pico-teide\/\">Gef\u00fchrte Besichtigung des Teide mit Genehmigung.<\/a><\/p>\n<div class=\"container\">\n \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img decoding=\"async\" class=\"imgstyle\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/61f2bf8b1fb5c74a13e68d08_parque-nacional-teide-senderismo-evento-twf2015.jpeg\" alt=\"teide\" \u00a0width=\"130\" height=\"130\"><br \/>\n \u00a0 \u00a0 \u00a0<\/div>\n<p> \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs2\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p class=\"textstyle\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a class=\"underline\" href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/excursion-pico-teide\/\">Entdecken Sie eine einzigartige Erfahrung.<\/a><br \/>\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p> \u00a0 \u00a0 \u00a0<\/p><\/div>\n<p> \u00a0<\/p><\/div>\n<\/div>\n<\/div>\n<h2>Einzigartige und unvergessliche Familienerlebnisse<\/h2>\n<p>Der Schulbeginn r\u00fcckt n\u00e4her, und genau in diesem Moment machen wir eine mentale Bestandsaufnahme, eine intime Inventur, ob wir unserem Bed\u00fcrfnis nach einem unvergleichlichen Sommer gerecht geworden sind.<\/p>\n<p>Neben Fernreisen entscheiden wir uns manchmal auch daf\u00fcr, den Sommer im eigenen Land zu genie\u00dfen. Dieses Jahr, <strong>Ich werde die einzigartigen Erlebnisse, die ich gemacht habe, behalten. &nbsp;<\/strong>Dazu geh\u00f6ren auch tolle Gespr\u00e4che, unz\u00e4hlige Aperitifs und atemberaubende Sonnenunterg\u00e4nge, und ich m\u00f6chte einen besonders hervorheben, der mich \u00fcberrascht hat. Diesen Sommer konnte ich mit meiner ganzen Familie auf dem Wanderweg mit Schildkr\u00f6ten schwimmen. <a href=\"https:\/\/sendaecoway.com\/de\/sendas\/snorkeling-con-avistamiento-de-tortugas-y-mantarrayas\/\">Schnorcheln mit Schildkr\u00f6ten und Mantarochen.<\/a><\/p>\n<p>Dies war ein Erlebnis, das sich aus vielen Gr\u00fcnden von allen anderen abhob. Der Hauptgrund war, dass ich so etwas noch nie zuvor gemacht hatte und ehrlich gesagt nicht wusste, dass es in den Gew\u00e4ssern von [Name des Gew\u00e4ssers] m\u00f6glich war. <a href=\"https:\/\/es.wikipedia.org\/wiki\/Tenerife\">Teneriffa<\/a>. Das Gef\u00fchl, mit diesen Tieren zu schwimmen und sie in ihrem freien Verhalten zu respektieren und zu bewundern, ist unbezahlbar.<\/p>\n<p>Dar\u00fcber hinaus vermittelte uns der Tauchlehrer, der uns w\u00e4hrend der Aktivit\u00e4t begleitete, seine Leidenschaft f\u00fcr das Tauchen, f\u00fcr das<strong> Wildtiere und Respekt vor dem Meeresboden. <\/strong>Das hat zweifellos dazu beigetragen, dass wir uns beim Schwimmen mit unseren geliebten Schildkr\u00f6ten von Teneriffa besonders gef\u00fchlt haben. Wir wissen, dass sie eines Tages abwandern werden, aber im Moment geh\u00f6ren sie zum Sommer unserer Familie dazu, und das werden wir immer in Erinnerung behalten!<\/p>\n<p>Die Schule beginnt wieder, und damit beginnt der Herbst. Die Tage werden k\u00fcrzer, und wir lassen unsere Badeanz\u00fcge vor\u00fcbergehend im Schrank. Meine Familie und ich werden aber weiterhin ein Auge auf die... <strong>neue Vorschl\u00e4ge f\u00fcr die Saison <\/strong>um weiterhin unvergleichliche, einzigartige Tourismuserlebnisse genie\u00dfen zu k\u00f6nnen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die R\u00fcckkehr zur Schule \u2764\ufe0f gibt uns das Gef\u00fchl von Sommernostalgie, aber wir werden uns immer an die einzigartigen Erlebnisse erinnern, die wir als Familie hatten.<\/p>","protected":false},"author":2,"featured_media":2634,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-2633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La vuelta al cole - Senda Ecoway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaecoway.com\/de\/blog\/zuruck-zur-schule\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vuelta al cole - Senda Ecoway\" \/>\n<meta property=\"og:description\" content=\"La vuelta al cole \u2764\ufe0f nos transmite el sentimiento de nostalgia del verano pero siempre recordaremos las experiencias \u00fanicas vividas en familia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaecoway.com\/de\/blog\/zuruck-zur-schule\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Ecoway\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T13:06:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T07:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MarSen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarSen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"},\"author\":{\"name\":\"MarSen\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\"},\"headline\":\"La vuelta al cole\",\"datePublished\":\"2024-10-01T13:06:23+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"},\"wordCount\":516,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\",\"name\":\"La vuelta al cole - Senda Ecoway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"datePublished\":\"2024-10-01T13:06:23+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg\",\"width\":400,\"height\":250,\"caption\":\"La vuelta al cole - Experiencias a tope\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/vuelta-al-cole\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vuelta al cole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"name\":\"Senda Ecoway\",\"description\":\"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendaecoway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\",\"name\":\"senda ecoway\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"width\":1024,\"height\":413,\"caption\":\"senda ecoway\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\",\"name\":\"MarSen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"caption\":\"MarSen\"},\"url\":\"https:\\\/\\\/sendaecoway.com\\\/de\\\/blog\\\/author\\\/marsen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zur\u00fcck zur Schule \u2013 \u00d6kowanderweg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaecoway.com\/de\/blog\/zuruck-zur-schule\/","og_locale":"de_DE","og_type":"article","og_title":"La vuelta al cole - Senda Ecoway","og_description":"La vuelta al cole \u2764\ufe0f nos transmite el sentimiento de nostalgia del verano pero siempre recordaremos las experiencias \u00fanicas vividas en familia.","og_url":"https:\/\/sendaecoway.com\/de\/blog\/zuruck-zur-schule\/","og_site_name":"Senda Ecoway","article_published_time":"2024-10-01T13:06:23+00:00","article_modified_time":"2024-10-14T07:39:23+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","type":"image\/jpeg"}],"author":"MarSen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MarSen","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#article","isPartOf":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"},"author":{"name":"MarSen","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52"},"headline":"La vuelta al cole","datePublished":"2024-10-01T13:06:23+00:00","dateModified":"2024-10-14T07:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"},"wordCount":516,"commentCount":0,"publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","articleSection":["blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/","url":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/","name":"Zur\u00fcck zur Schule \u2013 \u00d6kowanderweg","isPartOf":{"@id":"https:\/\/sendaecoway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","datePublished":"2024-10-01T13:06:23+00:00","dateModified":"2024-10-14T07:39:23+00:00","breadcrumb":{"@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#primaryimage","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7ed7a807c6c9a3805161_familia-1-1140x530-400x250-1.jpg","width":400,"height":250,"caption":"La vuelta al cole - Experiencias a tope"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaecoway.com\/blog\/vuelta-al-cole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaecoway.com\/"},{"@type":"ListItem","position":2,"name":"La vuelta al cole"}]},{"@type":"WebSite","@id":"https:\/\/sendaecoway.com\/#website","url":"https:\/\/sendaecoway.com\/","name":"Ecoway Pfad","description":"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.","publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaecoway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sendaecoway.com\/#organization","name":"senda ecoway","url":"https:\/\/sendaecoway.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","width":1024,"height":413,"caption":"senda ecoway"},"image":{"@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52","name":"MarSen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","url":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","caption":"MarSen"},"url":"https:\/\/sendaecoway.com\/de\/blog\/author\/marsen\/"}]}},"_links":{"self":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/comments?post=2633"}],"version-history":[{"count":1,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2633\/revisions"}],"predecessor-version":[{"id":3038,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2633\/revisions\/3038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media\/2634"}],"wp:attachment":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media?parent=2633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/categories?post=2633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/tags?post=2633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}