{"id":2575,"date":"2024-10-01T13:05:36","date_gmt":"2024-10-01T13:05:36","guid":{"rendered":"https:\/\/sendaecoway.com\/slow-food"},"modified":"2024-10-14T07:39:23","modified_gmt":"2024-10-14T07:39:23","slug":"langsame-kost","status":"publish","type":"post","link":"https:\/\/sendaecoway.com\/de\/blog\/slow-food\/","title":{"rendered":"Die Slow-Food-Bewegung und die Kunst, das zu sch\u00e4tzen, was wir essen"},"content":{"rendered":"<p>Die Welt dreht sich immer schneller. Schon von klein auf lernen wir, uns schnell anzuziehen, unsere Hausaufgaben schnell zu erledigen oder <strong>sogar, oft unbeabsichtigt, schnelles Essen<\/strong> und das eilige Bem\u00fchen, sich an eine Routine anzupassen, die stets von der Geschwindigkeit der Dinge gepr\u00e4gt ist.<\/p>\n<p>Angesichts all dieses t\u00e4glichen Wirbelsturms, und insbesondere in der <strong>Lebensmittelsektor<\/strong>, Es entstand mit voller Wucht vor mehr als einem Vierteljahrhundert.<strong> die Slow-Food-Bewegung, <\/strong>Oder, mit anderen Worten, die Kunst des achtsamen Essens, bei der man insbesondere Wert auf Qualit\u00e4t legt und daher die Herkunft der Rohstoffe, die Zutaten und die Art ihrer Zubereitung ber\u00fccksichtigt.<\/p>\n<p>Der von dieser Bewegung organisierte Salone del Gusto 2018 ging am 24. September in Turin zu Ende. <\/p>\n<p>Von der mexikanischen Milpa bis zur Ern\u00e4hrung der Massai in Kenia brachten indigene V\u00f6lker dies mit.<strong> Die Messe propagiert ihre Idee von gesunder Ern\u00e4hrung als Gegenmittel gegen Krankheiten des 21. Jahrhunderts., <\/strong>etwas, das sie seit jeher praktizieren.<\/p>\n<h2>Eine Bewegung, die in 160 L\u00e4ndern pr\u00e4sent ist<\/h2>\n<p>Die Slow-Food-Bewegung entstand 1986 auf Initiative des Italieners Carlo Petrini und einer Gruppe von Aktivisten. <strong>mit dem anf\u00e4nglichen Ziel der Verteidigung regionaler Traditionen, <\/strong>Gute Ern\u00e4hrung, kulinarischer Genuss sowie ein gem\u00e4chlicher Lebensrhythmus.<\/p>\n<p>Nach zwei Jahrzehnten Geschichte,<strong> Die Bewegung hat sich weiterentwickelt, um einem globalen Ansatz zum Thema Ern\u00e4hrung gerecht zu werden., <\/strong>das die starken Beziehungen anerkennt, die zwischen unseren Lebensmitteln, den Menschen, die sie produzieren, unserem Planeten, Politik und Kultur bestehen. <\/p>\n<p>Heute repr\u00e4sentiert Slow Food eine globale Bewegung, an der Tausende von Menschen und Projekte beteiligt sind. <strong>mehr als 160 L\u00e4nder<\/strong>.<\/p>\n<h2>Verantwortung bei den Mahlzeiten<\/h2>\n<p>Die Slow-Food-Bewegung setzt sich daf\u00fcr ein, das Verschwinden lokaler Esskulturen und -traditionen zu verhindern und dem Aufstieg beschleunigter Lebensstile entgegenzuwirken. <strong>um dem allgemeinen Desinteresse an den konsumierten Lebensmitteln entgegenzuwirken, <\/strong>seinen Ursprung und die Art und Weise, wie unsere Ern\u00e4hrungsgewohnheiten die Welt um uns herum beeinflussen.<\/p>\n<p>Wenn wir die Herkunft unserer Lebensmittel, die Menschen, die sie produzieren, und die Produktionsmethoden kennen, profitieren sowohl Kinder als auch Erwachsene davon.<strong> Wir werden lernen, Vergn\u00fcgen und Verantwortung in unseren t\u00e4glichen Entscheidungen zu verbinden.,<\/strong> sowie die sozialen und kulturellen Auswirkungen von Lebensmitteln wertzusch\u00e4tzen.<\/p>\n<h2>Wie Sie Ihren Geschmackssinn trainieren k\u00f6nnen<\/h2>\n<p>Slow Food f\u00fchrt in verschiedenen Teilen der Welt zahlreiche Bildungsprojekte durch, die sich von den meisten Ern\u00e4hrungsprogrammen unterscheiden, da sie auf der Idee basieren, dass Essen gleichbedeutend mit Genuss, Kultur und Geselligkeit ist. <\/p>\n<p>\u200d<strong>Diese Projekte richten sich an unterschiedliche Zielgruppen, von Kindern bis zu Erwachsenen.,<\/strong> einschlie\u00dflich Lehrer, Slow-Food-Mitglieder und die breite \u00d6ffentlichkeit. <\/p>\n<p>Dazu geh\u00f6ren unter anderem: Schulg\u00e4rten, gef\u00fchrte Verkostungen, Bauernhofbesuche, generations\u00fcbergreifender Wissensaustausch, praktische Workshops und gemeinsame Mahlzeiten mit den Erzeugern. <\/p>\n<p>Dar\u00fcber hinaus, <strong>Slow Food er\u00f6ffnete die Universit\u00e4t f\u00fcr Gastronomische Wissenschaften in Italien <\/strong>im Jahr 2004, um eine globale Perspektive auf die akademische Welt der Ern\u00e4hrung zu bieten.<\/p>\n<h2>Gutes, sauberes und faires Essen<\/h2>\n<p>Die<strong> Hauptziel der Slow-Food-Bewegung<\/strong> Es geht darum sicherzustellen, dass wir alle Zugang zu Lebensmitteln haben und diese genie\u00dfen k\u00f6nnen, die gut f\u00fcr uns, f\u00fcr diejenigen, die sie produzieren, und f\u00fcr den Planeten sind, und uns der Standardisierung von Geschmack und Kultur sowie der unbegrenzten Macht multinationaler Lebensmittelkonzerne und der industriellen Landwirtschaft entgegenzustellen.<\/p>\n<p>Ihr <strong>drei Grundprinzipien <\/strong>sind:<\/p>\n<p><strong>\u2022 Also: <\/strong>schmackhafte und frische saisonale Lebensmittel, die die Sinne befriedigen und Teil der <a href=\"https:\/\/es.wikipedia.org\/wiki\/Cultura_local\">lokale Kultur<\/a>.<\/p>\n<p><strong>\u2022 Sauber: <\/strong>Produktion und Konsum von Lebensmitteln, die weder der Umwelt noch dem Tierwohl oder der menschlichen Gesundheit schaden.<\/p>\n<p><strong>\u2022 Gerecht:<\/strong> erschwingliche Preise f\u00fcr die Verbraucher und eine faire Verg\u00fctung f\u00fcr die Produzenten.<\/p>\n<p>Diese Bewegung ist in vielen Teilen der Welt aktiv, um die Artenvielfalt der Lebensmittel zu sch\u00fctzen, Verbindungen zwischen Erzeugern und Verbrauchern herzustellen und das Bewusstsein in der Gesellschaft f\u00fcr die dringenden Probleme unseres Ern\u00e4hrungssystems zu sch\u00e4rfen. <\/p>\n<p>Und das liegt daran\u2026<strong> Nachhaltig und respektvoll essen<\/strong> Angesichts unserer Gegebenheiten ist das immer eine Option, die f\u00fcr uns in greifbarer N\u00e4he liegt.<\/p>\n<h2>Mach es langsam.<\/h2>\n<p>Ich habe k\u00fcrzlich von dem Verband erfahren. <strong>Cittaslow, <\/strong>Eine Idee, die vor zwei Jahrzehnten in einer kleinen Stadt in der Toskana entstand. <\/p>\n<p>Diese <strong>interessant<\/strong> <strong>Initiative<\/strong> Es handelt sich um einen Verband, der die Philosophie des Slow Food, die <a href=\"https:\/\/es.wikipedia.org\/wiki\/Ecococina\">\u00d6kogastronomie<\/a>, mit St\u00e4dten; es pl\u00e4diert daf\u00fcr, die Stadt selbst als entscheidenden Faktor f\u00fcr die Lebensqualit\u00e4t der Menschen und damit auch f\u00fcr ihr Gl\u00fcck zu betrachten. Offensichtlich, <strong>WAHR?<\/strong><\/p>\n<p>Das sind Ideen, die man wahrlich als \u201cgesunden Menschenverstand\u201d bezeichnen kann; solche Konzepte entstehen in einem historischen Moment, in dem alle von einem \u201cParadigmenwechsel\u201d sprechen.\u201d <strong>Ist Entwicklung durch Langsamkeit, durch Ruhe m\u00f6glich?<\/strong><\/p>\n<p>In einer Gesellschaft, in der alles Wertvolle materiell oder rund ist (siehe Fu\u00dfball), zieht uns alles in Richtung Leere; vom Immateriellen, von der Welt der Ideen, der Werte zu leben, wird zu einer wahren Meisterleistung.<\/p>\n<p>Diese Amtstr\u00e4ger \u2013 h\u00f6chstwahrscheinlich B\u00fcrgermeister \u2013, die entscheiden <strong>um sich Cittaslow anzuschlie\u00dfen<\/strong>, die sich zu <strong>einen Lebensstil wiederherstellen, verbessern und sch\u00fctzen<\/strong>, ein ruhiges, gem\u00e4chliches und beschauliches Leben. <\/p>\n<p>Haben sie sich jemals gefragt, was wirklich wesentlich ist, und haben sie die Bedeutung des Innehaltens, des Nachdenkens und des Weitblickens erkannt? Haben sie sich gefragt, was sie wirklich gl\u00fccklich gemacht hat?.<\/p>\n<p>All das muss gestoppt werden. <strong>Bewusstwerden<\/strong> vom Wechsel der Jahreszeiten, von der Wertsch\u00e4tzung handgefertigter Arbeit (wahrhaft mit Herz gemacht; Handwerkskunst), dem Wert der Kunst, der Authentizit\u00e4t von Produkten, dem Wert eines guten Essens oder eines guten Weins\u2026<\/p>\n<p>Ich nenne das alles <strong>Kultur.<\/strong><\/p>\n<ul>\n<li>Wissen <strong>Geruch<\/strong>.<\/li>\n<li>Wissen <strong>Geschmack<\/strong>.<\/li>\n<li>Wissen <strong>sehen<\/strong>.<\/li>\n<li>Wissen <strong>genie\u00dfen<\/strong>.<\/li>\n<\/ul>\n<p>Wir bei Senda sind \u00fcberzeugt, dass eine Entwicklung auf Basis dieser Werte m\u00f6glich ist. Sie sind der Schl\u00fcssel zu unserem Handeln und tragen nat\u00fcrlich auch unseren Teil zur Freude an einem Leben bei, das auf der Summe seiner Werte beruht. <a href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/\"><strong>Erfahrungen<\/strong><\/a><strong> <\/strong>die lohnenswert sind.<\/p>\n<h2>Nachhaltigkeit als zentraler Wert<\/h2>\n<p>Wenn auch Ihre Werte mit der Nachhaltigkeit Hand in Hand gehen, sollten Sie sich die folgenden verwandten Artikel nicht entgehen lassen:<\/p>\n<ul>\n<li><a href=\"https:\/\/sendaecoway.com\/de\/senda-erhalt-den-preis-fur-nachhaltigen-tourismus\/\">Senda erh\u00e4lt die Auszeichnung \u00abNachhaltiger Tourismus\u00bb.\u00bb<\/a><\/li>\n<li><a href=\"https:\/\/sendaecoway.com\/de\/blog\/verantwortungsvolles-surfen\/\">Verantwortungsvolles Surfen zur Verringerung der Umweltauswirkungen<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Die Slow-Food-Bewegung ist die Kunst des achtsamen Essens \ud83d\udc9a mit besonderem Augenmerk auf die Qualit\u00e4t der Lebensmittel und ihre lokale Herkunft.<\/p>","protected":false},"author":2,"featured_media":2576,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-2575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El movimiento slow food y el arte de valorar lo que comemos - Senda Ecoway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaecoway.com\/de\/blog\/langsame-kost\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El movimiento slow food y el arte de valorar lo que comemos - Senda Ecoway\" \/>\n<meta property=\"og:description\" content=\"El movimento Slow food es el arte de comer con atenci\u00f3n,\ud83d\udc9a valorando en especial la calidad de la alimentaci\u00f3n y su origen local.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaecoway.com\/de\/blog\/langsame-kost\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Ecoway\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T13:05:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T07:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MarSen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarSen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/\"},\"author\":{\"name\":\"MarSen\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\"},\"headline\":\"El movimiento slow food y el arte de valorar lo que comemos\",\"datePublished\":\"2024-10-01T13:05:36+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/\"},\"wordCount\":1100,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg\",\"articleSection\":[\"blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/\",\"name\":\"El movimiento slow food y el arte de valorar lo que comemos - Senda Ecoway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg\",\"datePublished\":\"2024-10-01T13:05:36+00:00\",\"dateModified\":\"2024-10-14T07:39:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg\",\"width\":400,\"height\":250,\"caption\":\"El movimiento slow food y el arte de valorar lo que comemos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/slow-food\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El movimiento slow food y el arte de valorar lo que comemos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"name\":\"Senda Ecoway\",\"description\":\"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendaecoway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\",\"name\":\"senda ecoway\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"width\":1024,\"height\":413,\"caption\":\"senda ecoway\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\",\"name\":\"MarSen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"caption\":\"MarSen\"},\"url\":\"https:\\\/\\\/sendaecoway.com\\\/de\\\/blog\\\/author\\\/marsen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Slow-Food-Bewegung und die Kunst, das, was wir essen, wertzusch\u00e4tzen \u2013 Senda Ecoway","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaecoway.com\/de\/blog\/langsame-kost\/","og_locale":"de_DE","og_type":"article","og_title":"El movimiento slow food y el arte de valorar lo que comemos - Senda Ecoway","og_description":"El movimento Slow food es el arte de comer con atenci\u00f3n,\ud83d\udc9a valorando en especial la calidad de la alimentaci\u00f3n y su origen local.","og_url":"https:\/\/sendaecoway.com\/de\/blog\/langsame-kost\/","og_site_name":"Senda Ecoway","article_published_time":"2024-10-01T13:05:36+00:00","article_modified_time":"2024-10-14T07:39:23+00:00","og_image":[{"width":400,"height":250,"url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg","type":"image\/jpeg"}],"author":"MarSen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MarSen","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#article","isPartOf":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/"},"author":{"name":"MarSen","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52"},"headline":"El movimiento slow food y el arte de valorar lo que comemos","datePublished":"2024-10-01T13:05:36+00:00","dateModified":"2024-10-14T07:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/"},"wordCount":1100,"commentCount":0,"publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg","articleSection":["blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendaecoway.com\/blog\/slow-food\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/","url":"https:\/\/sendaecoway.com\/blog\/slow-food\/","name":"Die Slow-Food-Bewegung und die Kunst, das, was wir essen, wertzusch\u00e4tzen \u2013 Senda Ecoway","isPartOf":{"@id":"https:\/\/sendaecoway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#primaryimage"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg","datePublished":"2024-10-01T13:05:36+00:00","dateModified":"2024-10-14T07:39:23+00:00","breadcrumb":{"@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendaecoway.com\/blog\/slow-food\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#primaryimage","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b860e4ffa9c9bc07449f3_slow-food-1-400x250-1.jpg","width":400,"height":250,"caption":"El movimiento slow food y el arte de valorar lo que comemos"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaecoway.com\/blog\/slow-food\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaecoway.com\/"},{"@type":"ListItem","position":2,"name":"El movimiento slow food y el arte de valorar lo que comemos"}]},{"@type":"WebSite","@id":"https:\/\/sendaecoway.com\/#website","url":"https:\/\/sendaecoway.com\/","name":"Ecoway Pfad","description":"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.","publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaecoway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sendaecoway.com\/#organization","name":"senda ecoway","url":"https:\/\/sendaecoway.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","width":1024,"height":413,"caption":"senda ecoway"},"image":{"@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52","name":"MarSen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","url":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","caption":"MarSen"},"url":"https:\/\/sendaecoway.com\/de\/blog\/author\/marsen\/"}]}},"_links":{"self":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/comments?post=2575"}],"version-history":[{"count":1,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2575\/revisions"}],"predecessor-version":[{"id":3049,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2575\/revisions\/3049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media\/2576"}],"wp:attachment":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media?parent=2575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/categories?post=2575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/tags?post=2575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}