{"id":2295,"date":"2024-10-01T13:01:48","date_gmt":"2024-10-01T13:01:48","guid":{"rendered":"https:\/\/sendaecoway.com\/pintando-con-vino"},"modified":"2024-10-14T07:39:25","modified_gmt":"2024-10-14T07:39:25","slug":"malen-mit-wein","status":"publish","type":"post","link":"https:\/\/sendaecoway.com\/de\/blog\/pintando-con-vino\/","title":{"rendered":"Kunst und Wein | Marta Ara\u00f1\u00f3, die K\u00fcnstlerin, die Rotwein als Tinte verwendet"},"content":{"rendered":"<h4><strong>Senda: Wie haben Sie die Kunst des Malens mit Wein entdeckt?<\/strong><\/h4>\n<p><em>Marder:<\/em> Nachdem ich viele Jahre in der Welt der Malerei t\u00e4tig war und in einer Weinregion gelebt hatte, wollte ich die Kunst, die in einer Weinflasche existiert, in Kunst auf einem leeren Blatt Papier verwandeln; nach vielen Versuchen und der Erkenntnis, dass die Werke Bestand hatten, beschloss ich, diesen Weg einzuschlagen, dem ich mich seit 5 Jahren professionell widme.<\/p>\n<h4><strong>Bis vor Kurzem haben Sie professionell nur mit Pastellkreide gezeichnet, welche Technik bevorzugen Sie?<\/strong><\/h4>\n<p>Ich f\u00fchle mich mit beidem sehr wohl, aber im Moment widme ich mich ausschlie\u00dflich dem Malen mit Wein.<\/p>\n<h4><strong>Haben Sie auch Werke f\u00fcr andere Teile der Welt geschaffen?<\/strong><\/h4>\n<p>Ja, ich habe Arbeit in den USA, den Niederlanden, Frankreich, Italien und Gro\u00dfbritannien.<\/p>\n<h4><strong>Worum geht es beim Live-Malen?<\/strong><\/h4>\n<p>Es handelt sich um eine Aktivit\u00e4t, die ich bei Verkostungen, Weinproben und Veranstaltungen durchf\u00fchre, bei denen Wein im Mittelpunkt steht. Dabei geht es darum, in kurzer Zeit (zwischen 1 und 2 Stunden) ein Kunstwerk zu schaffen. Das Ergebnis zeigt, wie ein live entstandenes Kunstwerk genauso originell sein kann wie eines, das im Atelier entsteht \u2013 mit weniger Aufwand, aber nicht weniger Qualit\u00e4t und Originalit\u00e4t.<\/p>\n<figure class=\"w-richtext-figure-type-video w-richtext-align-center\" style=\"padding-bottom:33.75%\" data-rt-type=\"video\" data-rt-align=\"center\" data-rt-max-width=\"\" data-rt-max-height=\"33.75%\" data-rt-dimensions=\"0:0\" data-page-url=\"\">\n<div><iframe src=\"https:\/\/secure-embed.rtve.es\/drmn\/embed\/video\/4372670\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/figure>\n<figure class=\"w-richtext-figure-type-image w-richtext-align-center\" data-rt-type=\"image\" data-rt-align=\"center\">\n<div><img decoding=\"async\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7b46a4bd08044dfcef1d_logoRTVEes.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"auto\"><\/div><figcaption><a href=\"http:\/\/www.rtve.es\/alacarta\/videos\/punts-de-vista\/punts-vista-pintora-marta-arano\/4372670\/\"><strong>Die Malerin Marta Ara\u00f1\u00f3<\/strong><\/a><\/figcaption><\/figure>\n<div data-rt-embed-type='true'><link href=\"https:\/\/fonts.googleapis.com\/icon?family=Material+Icons\" rel=\"stylesheet\">\n<meta name=\"viewport\" content=\"width=device-width, initial-scale=1.0\"><\/p>\n<style>\n.myDiv {\nmargin-left: 15px;\n \u00a0border-radius: 5px;\n \u00a0background-color:#bdd5d4;\n \u00a0text-align: left;\n \u00a0border:2px solid #539796;\n}\n.textstyle{\nfont-family: Arial, Helvetica, sans-serif;\nfont-size:15px;\n}\n.underline{\ncolor:#539796;\ntext-decoration: none;\n}<\/p>\n<p>.imgstyle{\nborder-radius: 5px;\nwidth:100%;<\/p>\n<p>}\n.textt{\ntext-align:left;\nmargin-top:30px;\nmargin-left:20px;\nwidth:100%;\n}\n.space{\nmargin-left:20px;\nmargin-right:20px;\n}<\/p>\n<p>.styledivvs{\ndisplay:inline-block;\nvertical-align:top;\nfloat:center;\n}\n.styledivvs2{\ndisplay:inline-block;\nbackground-color:#fff;\nheight:130px;\nwidth:140px;\nborder-radius:5px;\npadding-top:40px;\n}\n.container{\nalign-content:center;\ntext-align:center;\npadding-bottom:20px;\ntransition: all 0.5s linear;\n}<\/p>\n<p>\/*.container:hover{\ntransform:scale(1,1);\n}*\/\n.container:hover {\n \u00a0transform: scale(1.1);\n}<\/p>\n<p>.material-icons{\npadding-top:20px;\n}\na:hover {\ntext-decoration: underline;\ncolor:#175453;\n}<\/p>\n<\/style>\n<div class=\"myDiv\">\n<p> \u00a0<\/p>\n<p class=\"textt\"><b><span class=\"material-icons\"><br \/>\n \u00a0Gl\u00fchbirne<\/span>Welchem Plan folgen Sie in Ihrem Urlaub?<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Verpassen Sie nicht das Erlebnis <b>Ausflug zum Teide-Gipfel: zu Fu\u00df oder mit der Seilbahn<\/b><\/p>\n<p> \u00a0<\/p>\n<p class=\"space\">Lernen Sie den meistbesuchten Nationalpark Europas kennen und besteigen Sie den h\u00f6chsten Gipfel Spaniens. \u00dcberschreiten Sie Ihre Grenzen auf diesem Ausflug von <b>Besteigung des Gipfels des Teide mit Genehmigung.<\/b><\/p>\n<p class=\"space\">Wenn Sie ein einzigartiges und umweltfreundliches Erlebnis erleben und au\u00dferdem mit einem Senda-F\u00fchrer den Teide-Nationalpark kennen lernen m\u00f6chten, der von der UNESCO zum Weltkulturerbe erkl\u00e4rt wurde, dann sind Sie hier genau richtig. <b>Unesco-Welterbe<\/b>buchen Sie Ihren Platz f\u00fcr eine <a class=\"underline\" href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/excursion-pico-teide\/\">Gef\u00fchrte Besichtigung des Teide mit Genehmigung.<\/a><\/p>\n<div class=\"container\">\n \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<img decoding=\"async\" class=\"imgstyle\" src=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/61f2bf8b1fb5c74a13e68d08_parque-nacional-teide-senderismo-evento-twf2015.jpeg\" alt=\"teide\" \u00a0width=\"130\" height=\"130\"><br \/>\n \u00a0 \u00a0 \u00a0<\/div>\n<p> \u00a0 \u00a0 \u00a0<\/p>\n<div class=\"styledivvs2\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p class=\"textstyle\">\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a class=\"underline\" href=\"https:\/\/sendaecoway.com\/de\/erfahrungen\/excursion-pico-teide\/\">Entdecken Sie eine einzigartige Erfahrung.<\/a><br \/>\n \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<\/p>\n<p> \u00a0 \u00a0 \u00a0<\/p><\/div>\n<p> \u00a0<\/p><\/div>\n<\/div>\n<\/div>\n<h4><strong>Ver\u00e4ndert sich die Farbe des Weins stark, wenn er auf Papier dargestellt wird?<\/strong><\/h4>\n<p>Jeder Wein, jeder Jahrgang, jede Rebsorte hat seinen eigenen Charakter, der durch die Oxidation noch verst\u00e4rkt wird und dem Wein so eine gr\u00f6\u00dfere Sch\u00f6nheit verleiht.<\/p>\n<h4><strong>Mit welcher Weinsorte arbeiten Sie am liebsten? Warum?<\/strong><\/h4>\n<p>Jeder Wein hat seinen eigenen Reiz und verh\u00e4lt sich auf dem Teller anders; sie alle faszinieren mich und erzeugen stets eine Ungewissheit im Endergebnis, die die Entstehung des Werkes umso spannender macht.<\/p>\n<h4><strong>Wie wichtig ist die Pflege der Weinberge f\u00fcr Ihre Arbeit?<\/strong><\/h4>\n<p>Ich w\u00fcrde sagen, es ist genau umgekehrt; f\u00fcr mich ist die Arbeit des Winzers, sein Einsatz und seine Ausdauer so wichtig, dass es meine Pflicht ist, aus Respekt vor seiner Arbeit und seinem Engagement mit seinem Wein eine gute Tat zu vollbringen.<\/p>\n<h4><strong>Sie bieten Workshops f\u00fcr alle Altersgruppen an. Gibt es Unterschiede zwischen ihnen?<\/strong><\/h4>\n<p>Ja, ich leite verschiedene Workshops, die stets auf das Alter der Teilnehmenden abgestimmt sind. Kinder und Jugendliche malen mit alkoholfreiem Wein und recyceln die Korken von Weinflaschen. Erwachsene besprechen den verwendeten Wein und verkosten ihn, w\u00e4hrend sie damit malen. Au\u00dferdem biete ich Workshops f\u00fcr Familien an, in denen Kreativit\u00e4t und Zusammenarbeit von Eltern und Kindern die Kunst zu ihrem sch\u00f6nsten Ausdruck bringen. <\/p>\n<p>Eines m\u00f6chte ich immer wieder betonen: Um mit der Weinmalerei zu experimentieren, muss man nicht zeichnen k\u00f6nnen, sondern nur experimentierfreudig sein und Freude an dieser neuen Technik haben.<\/p>\n<p>Willkommen im Kunstatelier! Ein Glas Cava f\u00fcr die Erwachsenen und Traubensaft f\u00fcr die Kinder. Besuchen Sie die Werkstatt, sehen Sie Filme \u00fcber die Weinregion, erfahren Sie mehr \u00fcber die Technik des Malens mit Wein \u2013 ein sehr dynamischer und unterhaltsamer Praxisworkshop. Zum Abschluss genie\u00dfen wir einen Brunch im Garten.<\/p>\n<h4><strong>Halten Sie es f\u00fcr interessant, diese Aktivit\u00e4t in katalanische Schulen einzuf\u00fchren?<\/strong><\/h4>\n<p>Ja, ich setze sie bereits in einigen davon ein, und die Ergebnisse sind wirklich beeindruckend. In diesen Workshops erkunden wir die Weinkultur, lernen die Landschaften, die verschiedenen Wachstumszyklen der Reben und die Farben der Rebsorten aus einer anderen Perspektive kennen \u2013 aus der Welt der Kunst.<\/p>\n<h4><strong>Welche Projekte m\u00f6chten Sie als N\u00e4chstes in Angriff nehmen?<\/strong><\/h4>\n<p>Ich habe viele Projekte und den starken Wunsch, diese Erfahrung mit vielen Menschen zu teilen, indem ich ganz individuelle Aktivit\u00e4ten im Bereich der Weinmalerei gestalte, unsere Weinregion pr\u00e4sentiere und Respekt f\u00fcr die Umwelt vermittle. <\/p>\n<p>Ich freue mich auf Ihren Besuch in meinem Malatelier oder darauf, Sie bei einer der von mir organisierten Veranstaltungen in ganz Katalonien oder auf der Iberischen Halbinsel zu sehen. <\/p>\n<p>Ich bereite derzeit auch eine Ausstellung mit Weinen aus aller Welt vor und genie\u00dfe dabei Sorten und Nuancen, die mir bisher unbekannt waren. <\/p>\n<p>Diese Ausstellung wird auf der Iberischen Halbinsel und im Ausland gezeigt. Weitere Informationen zu meinen Aktivit\u00e4ten und meiner Arbeit finden Sie auf meiner Website. <a href=\"http:\/\/tintaivi.com\/\">tintaivi.com<\/a> Oder ihr findet mich in den sozialen Medien unter tintaivi auf Facebook und Twitter oder tinta_i_vi auf Instagram.<\/p>","protected":false},"excerpt":{"rendered":"<p>Marta Ara\u00f1\u00f3 zeigt uns die kuriose und faszinierende Kunst des Malens mit Rotwein als Tinte. Ein H\u00f6hepunkt in der Arbeit der Winzer.<\/p>","protected":false},"author":2,"featured_media":2296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[87],"tags":[],"class_list":["post-2295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta - Senda Ecoway<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sendaecoway.com\/de\/blog\/malen-mit-wein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta - Senda Ecoway\" \/>\n<meta property=\"og:description\" content=\"Marta Ara\u00f1\u00f3 nos ense\u00f1a el curioso y fascinante arte de pintar utilizando vino tinto como tinta. Una puesta en valor del trabajo de los vinicultores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sendaecoway.com\/de\/blog\/malen-mit-wein\/\" \/>\n<meta property=\"og:site_name\" content=\"Senda Ecoway\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-01T13:01:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T07:39:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"335\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"MarSen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"MarSen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/\"},\"author\":{\"name\":\"MarSen\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\"},\"headline\":\"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta\",\"datePublished\":\"2024-10-01T13:01:48+00:00\",\"dateModified\":\"2024-10-14T07:39:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/\"},\"wordCount\":879,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png\",\"articleSection\":[\"blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/\",\"name\":\"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta - Senda Ecoway\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png\",\"datePublished\":\"2024-10-01T13:01:48+00:00\",\"dateModified\":\"2024-10-14T07:39:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png\",\"width\":335,\"height\":250,\"caption\":\"vino como tinta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/blog\\\/pintando-con-vino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sendaecoway.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#website\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"name\":\"Senda Ecoway\",\"description\":\"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.\",\"publisher\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sendaecoway.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#organization\",\"name\":\"senda ecoway\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png\",\"width\":1024,\"height\":413,\"caption\":\"senda ecoway\"},\"image\":{\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/#\\\/schema\\\/person\\\/8aa6cb09cdc9a3d253edba48060bbb52\",\"name\":\"MarSen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"url\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"contentUrl\":\"https:\\\/\\\/sendaecoway.com\\\/wp-content\\\/litespeed\\\/avatar\\\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793\",\"caption\":\"MarSen\"},\"url\":\"https:\\\/\\\/sendaecoway.com\\\/de\\\/blog\\\/author\\\/marsen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kunst und Wein | Marta Ara\u00f1\u00f3, die K\u00fcnstlerin, die Rotwein als Tinte verwendet \u2013 Senda Ecoway","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sendaecoway.com\/de\/blog\/malen-mit-wein\/","og_locale":"de_DE","og_type":"article","og_title":"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta - Senda Ecoway","og_description":"Marta Ara\u00f1\u00f3 nos ense\u00f1a el curioso y fascinante arte de pintar utilizando vino tinto como tinta. Una puesta en valor del trabajo de los vinicultores.","og_url":"https:\/\/sendaecoway.com\/de\/blog\/malen-mit-wein\/","og_site_name":"Senda Ecoway","article_published_time":"2024-10-01T13:01:48+00:00","article_modified_time":"2024-10-14T07:39:25+00:00","og_image":[{"width":335,"height":250,"url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png","type":"image\/png"}],"author":"MarSen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"MarSen","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#article","isPartOf":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/"},"author":{"name":"MarSen","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52"},"headline":"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta","datePublished":"2024-10-01T13:01:48+00:00","dateModified":"2024-10-14T07:39:25+00:00","mainEntityOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/"},"wordCount":879,"commentCount":0,"publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png","articleSection":["blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/","url":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/","name":"Kunst und Wein | Marta Ara\u00f1\u00f3, die K\u00fcnstlerin, die Rotwein als Tinte verwendet \u2013 Senda Ecoway","isPartOf":{"@id":"https:\/\/sendaecoway.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#primaryimage"},"image":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#primaryimage"},"thumbnailUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png","datePublished":"2024-10-01T13:01:48+00:00","dateModified":"2024-10-14T07:39:25+00:00","breadcrumb":{"@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#primaryimage","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619b7bed6a3431022dca6d0f_Tinta-Vino-y-Brunch-en-Estudio-de-Arte-1-335x250-1.png","width":335,"height":250,"caption":"vino como tinta"},{"@type":"BreadcrumbList","@id":"https:\/\/sendaecoway.com\/blog\/pintando-con-vino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sendaecoway.com\/"},{"@type":"ListItem","position":2,"name":"Arte y Vino | Marta Ara\u00f1\u00f3, la artista que usa vino tinto como tinta"}]},{"@type":"WebSite","@id":"https:\/\/sendaecoway.com\/#website","url":"https:\/\/sendaecoway.com\/","name":"Ecoway Pfad","description":"Ofrecemos experiencias sostenibles con rutas guiadas por gu\u00edas locales y actividades en peque\u00f1os grupos.","publisher":{"@id":"https:\/\/sendaecoway.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sendaecoway.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sendaecoway.com\/#organization","name":"senda ecoway","url":"https:\/\/sendaecoway.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/","url":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/uploads\/2024\/10\/619797bf655bee433c2dff8c_LOGOTIPO-OFICIAL-2-1024x413-1.png","width":1024,"height":413,"caption":"senda ecoway"},"image":{"@id":"https:\/\/sendaecoway.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/sendaecoway.com\/#\/schema\/person\/8aa6cb09cdc9a3d253edba48060bbb52","name":"MarSen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","url":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","contentUrl":"https:\/\/sendaecoway.com\/wp-content\/litespeed\/avatar\/7eaaec2207564cc1217f5a83e3d00d0c.jpg?ver=1788358793","caption":"MarSen"},"url":"https:\/\/sendaecoway.com\/de\/blog\/author\/marsen\/"}]}},"_links":{"self":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/comments?post=2295"}],"version-history":[{"count":1,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2295\/revisions"}],"predecessor-version":[{"id":3075,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/posts\/2295\/revisions\/3075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media\/2296"}],"wp:attachment":[{"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/media?parent=2295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/categories?post=2295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sendaecoway.com\/de\/wp-json\/wp\/v2\/tags?post=2295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}